{"id":29015,"date":"2005-01-17T09:36:43","date_gmt":"2005-01-17T09:36:43","guid":{"rendered":"http:\/\/www.aceguarulhos.com.br\/blog\/?p=29015"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-30T03:00:00","slug":"acsp-discute-cadastro-positivo-com-governo","status":"publish","type":"post","link":"https:\/\/www.aceguarulhos.com.br\/blog\/acsp-discute-cadastro-positivo-com-governo\/","title":{"rendered":"ACSP discute cadastro positivo com governo"},"content":{"rendered":"<p><P>Qual a diferen\u00e7a entre os juros cobrados de um consumidor que paga em dia um empr\u00e9stimo tomado no mercado e os embutidos no cr\u00e9dito concedido a um mau pagador? Nenhuma. Com o objetivo de premiar o bom pagador com juros menores, a Associa\u00e7\u00e3o Comercial de S\u00e3o Paulo (ACSP) vem trabalhando, nos \u00faltimos dois anos, na cria\u00e7\u00e3o do cadastro positivo &#8211; um hist\u00f3rico do consumidor no que se refere \u00e0 pontualidade no pagamento de d\u00edvidas assumidas no mercado, seja em bancos ou no varejo, financiando compras. <\/P><P>Na sexta-feira, 14, o projeto para a cria\u00e7\u00e3o do cadastro positivo elaborado pela ACSP foi discutido em S\u00e3o Paulo com o secret\u00e1rio de Pol\u00edtica Econ\u00f4mica do Minist\u00e9rio da Fazenda, Marcos Lisboa. <\/P><P>Para Lisboa, a iniciativa da Associa\u00e7\u00e3o Comercial \u00e9 muito importante na medida em que o cadastro permitir\u00e1 reduzir os juros dos empr\u00e9stimos, beneficiando especialmente os consumidores com renda menor. <\/P><P><STRONG>Impulso <\/STRONG>&#8211; Marcos Lisboa defendeu o cadastro positivo lembrando que apenas a cria\u00e7\u00e3o do cr\u00e9dito consignado em folha de pagamento, que oferece ao banco risco menor, resultou num acr\u00e9scimo de mais R$ 12 bilh\u00f5es no volume de cr\u00e9dito, nos \u00faltimos 12 meses. <\/P><P>&#8220;E com uma queda sens\u00edvel nas taxas para esse p\u00fablico, que antes era de 5% a 8%, para 2,8% em m\u00e9dia ao m\u00eas, uma queda significativa apenas com uma medida simples&#8221;, disse Lisboa. <\/P><P>A vantagem do cadastro positivo, afirmou o secret\u00e1rio, \u00e9 que ele leva em conta o hist\u00f3rico de pagamentos do consumidor. &#8220;Sem isso, quem paga o pre\u00e7o da falta de informa\u00e7\u00e3o n\u00e3o \u00e9 o mau pagador, mas o bom pagador&#8221;, insistiu o secret\u00e1rio. <\/P><P><STRONG>Nas alturas <\/STRONG>&#8211; No Brasil, o spread &#8211; diferen\u00e7a entre os juros pagos pelas institui\u00e7\u00f5es financeiras na capta\u00e7\u00e3o de recursos e as taxas cobradas nos empr\u00e9stimos a pessoas fisicas e empresas &#8211; est\u00e1 entre os maiores do mundo. Os juros cobrados nas opera\u00e7\u00f5es de cr\u00e9dito pessoal com recursos livres de pessoas f\u00edsicas chegou a 72% ao ano em outubro de 2004, segundo levantamento do Banco Central. Era de 61% em meados de 2003 e de 49% na metade de 2002. J\u00e1 as empresas arcaram, em igual per\u00edodo, com 31% de juros ao ano, no ano passado, at\u00e9 outubro. Com o projeto do cadastro positivo esses juros podem cair. <\/P><P>&#8220;\u00c9 um projeto de defesa do consumidor, sobretudo para o bom pagador de menor renda, que tem apenas o nome como garantia&#8221;, disse Guilherme Afif Domingos, presidente da Associa\u00e7\u00e3o Comercial de S\u00e3o Paulo. <\/P><P>Segundo Guilherme Afif, o spread \u00e9 alto porque embute em seu custo 35% de cunha fiscal e quase 70% de taxa de risco, gerada da falta de seguran\u00e7a jur\u00eddica e da inadimpl\u00eancia. <\/P><P>&#8220;Como o patrim\u00f4nio do cidad\u00e3o \u00e9 sua reputa\u00e7\u00e3o, a informa\u00e7\u00e3o apenas do cadastro negativo (aquele em que aparecem os d\u00e9bitos do consumidor ou os pagamentos feitos com atraso) impede que o bom pagador se beneficie&#8221;, diz Afif. <\/P><P>Para o presidente da ACSP, a maioria dos consumidores paga seus compromisssos em dia, mas pode acontecer um atraso espor\u00e1dico, com motivo justificado, como a perda tempor\u00e1ria de emprego e, conseq\u00fcentemente, de renda. <\/P><P>&#8220;Mas sem uma an\u00e1lise baseada no cadastro positivo ningu\u00e9m conhecer\u00e1 seu hist\u00f3rico de bom pagador&#8221;, continua Afif. <\/P><P>A ado\u00e7\u00e3o do cadastro positivo, diz Afif, pode reduzir em at\u00e9 50% a taxa de risco do consumidor. &#8220;\u00c9 interesse do com\u00e9rcio conceder cada vez mais cr\u00e9dito&#8221;, diz o executivo. Como o projeto j\u00e1 representa um consenso entre governo e iniciativa privada, para Afif &#8220;sua aprova\u00e7\u00e3o pelo Congresso fica mais f\u00e1cil&#8221;, completa. <\/P><P><STRONG>S\u00e9rgio Leopoldo Rodrigues<\/STRONG><\/P><\/p>\n","protected":false},"excerpt":{"rendered":"Qual a diferen\u00e7a entre os juros cobrados de um consumidor que paga em dia um empr\u00e9stimo tomado no mercado e os embutidos no \n<a class=\"moretag\" href=\"https:\/\/www.aceguarulhos.com.br\/blog\/acsp-discute-cadastro-positivo-com-governo\/\"> [...]<\/a>","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-29015","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ACSP discute cadastro positivo com governo - ACE-Guarulhos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aceguarulhos.com.br\/blog\/acsp-discute-cadastro-positivo-com-governo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ACSP discute cadastro positivo com governo - ACE-Guarulhos\" \/>\n<meta property=\"og:description\" content=\"Qual a diferen\u00e7a entre os juros cobrados de um consumidor que paga em dia um empr\u00e9stimo tomado no mercado e os embutidos no\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aceguarulhos.com.br\/blog\/acsp-discute-cadastro-positivo-com-governo\/\" \/>\n<meta property=\"og:site_name\" content=\"ACE-Guarulhos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aceguarulhos\/\" \/>\n<meta property=\"article:published_time\" content=\"2005-01-17T09:36:43+00:00\" \/>\n<meta name=\"author\" content=\"Assessoria de Imprensa ACE-Guarulhos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Assessoria de Imprensa ACE-Guarulhos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/acsp-discute-cadastro-positivo-com-governo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/acsp-discute-cadastro-positivo-com-governo\\\/\"},\"author\":{\"name\":\"Assessoria de Imprensa ACE-Guarulhos\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/6983b51bad37489989e4f09698c26237\"},\"headline\":\"ACSP discute cadastro positivo com governo\",\"datePublished\":\"2005-01-17T09:36:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/acsp-discute-cadastro-positivo-com-governo\\\/\"},\"wordCount\":620,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/acsp-discute-cadastro-positivo-com-governo\\\/\",\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/acsp-discute-cadastro-positivo-com-governo\\\/\",\"name\":\"ACSP discute cadastro positivo com governo - ACE-Guarulhos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#website\"},\"datePublished\":\"2005-01-17T09:36:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/acsp-discute-cadastro-positivo-com-governo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/acsp-discute-cadastro-positivo-com-governo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/acsp-discute-cadastro-positivo-com-governo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ACSP discute cadastro positivo com governo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/\",\"name\":\"ACE-Guarulhos\",\"description\":\"A ACE-Guarulhos \u00e9 uma associa\u00e7\u00e3o que ap\u00f3ia os empres\u00e1rios guarulhenses atrav\u00e9s da representa\u00e7\u00e3o, da gera\u00e7\u00e3o de neg\u00f3cios e presta\u00e7\u00e3o de servi\u00e7os.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#organization\",\"name\":\"ACE-Guarulhos\",\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-aceguarulhos-2018.png\",\"contentUrl\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-aceguarulhos-2018.png\",\"width\":419,\"height\":76,\"caption\":\"ACE-Guarulhos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aceguarulhos\\\/\",\"https:\\\/\\\/br.linkedin.com\\\/in\\\/ace-guarulhos-b9a97093\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/aceguarulhos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/6983b51bad37489989e4f09698c26237\",\"name\":\"Assessoria de Imprensa ACE-Guarulhos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g\",\"caption\":\"Assessoria de Imprensa ACE-Guarulhos\"},\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/author\\\/assessoria-de-imprensa-ace-guarulhos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ACSP discute cadastro positivo com governo - ACE-Guarulhos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aceguarulhos.com.br\/blog\/acsp-discute-cadastro-positivo-com-governo\/","og_locale":"pt_BR","og_type":"article","og_title":"ACSP discute cadastro positivo com governo - ACE-Guarulhos","og_description":"Qual a diferen\u00e7a entre os juros cobrados de um consumidor que paga em dia um empr\u00e9stimo tomado no mercado e os embutidos no","og_url":"https:\/\/www.aceguarulhos.com.br\/blog\/acsp-discute-cadastro-positivo-com-governo\/","og_site_name":"ACE-Guarulhos","article_publisher":"https:\/\/www.facebook.com\/aceguarulhos\/","article_published_time":"2005-01-17T09:36:43+00:00","author":"Assessoria de Imprensa ACE-Guarulhos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Assessoria de Imprensa ACE-Guarulhos","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/acsp-discute-cadastro-positivo-com-governo\/#article","isPartOf":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/acsp-discute-cadastro-positivo-com-governo\/"},"author":{"name":"Assessoria de Imprensa ACE-Guarulhos","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#\/schema\/person\/6983b51bad37489989e4f09698c26237"},"headline":"ACSP discute cadastro positivo com governo","datePublished":"2005-01-17T09:36:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/acsp-discute-cadastro-positivo-com-governo\/"},"wordCount":620,"commentCount":0,"publisher":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/acsp-discute-cadastro-positivo-com-governo\/","url":"https:\/\/www.aceguarulhos.com.br\/blog\/acsp-discute-cadastro-positivo-com-governo\/","name":"ACSP discute cadastro positivo com governo - ACE-Guarulhos","isPartOf":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#website"},"datePublished":"2005-01-17T09:36:43+00:00","breadcrumb":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/acsp-discute-cadastro-positivo-com-governo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aceguarulhos.com.br\/blog\/acsp-discute-cadastro-positivo-com-governo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/acsp-discute-cadastro-positivo-com-governo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.aceguarulhos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ACSP discute cadastro positivo com governo"}]},{"@type":"WebSite","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#website","url":"https:\/\/www.aceguarulhos.com.br\/blog\/","name":"ACE-Guarulhos","description":"A ACE-Guarulhos \u00e9 uma associa\u00e7\u00e3o que ap\u00f3ia os empres\u00e1rios guarulhenses atrav\u00e9s da representa\u00e7\u00e3o, da gera\u00e7\u00e3o de neg\u00f3cios e presta\u00e7\u00e3o de servi\u00e7os.","publisher":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aceguarulhos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#organization","name":"ACE-Guarulhos","url":"https:\/\/www.aceguarulhos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-content\/uploads\/2017\/12\/logo-aceguarulhos-2018.png","contentUrl":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-content\/uploads\/2017\/12\/logo-aceguarulhos-2018.png","width":419,"height":76,"caption":"ACE-Guarulhos"},"image":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aceguarulhos\/","https:\/\/br.linkedin.com\/in\/ace-guarulhos-b9a97093","https:\/\/www.youtube.com\/user\/aceguarulhos"]},{"@type":"Person","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#\/schema\/person\/6983b51bad37489989e4f09698c26237","name":"Assessoria de Imprensa ACE-Guarulhos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g","caption":"Assessoria de Imprensa ACE-Guarulhos"},"url":"https:\/\/www.aceguarulhos.com.br\/blog\/author\/assessoria-de-imprensa-ace-guarulhos\/"}]}},"wps_subtitle":"","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/posts\/29015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=29015"}],"version-history":[{"count":0,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/posts\/29015\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=29015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=29015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=29015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}