{"id":28996,"date":"2005-01-10T07:57:03","date_gmt":"2005-01-10T07:57:03","guid":{"rendered":"http:\/\/www.aceguarulhos.com.br\/blog\/?p=28996"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-30T03:00:00","slug":"pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento","status":"publish","type":"post","link":"https:\/\/www.aceguarulhos.com.br\/blog\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\/","title":{"rendered":"Pequena empresa cresce, mas a custos altos e ritmo lento"},"content":{"rendered":"<p><P>Mais empregos, aumento do uso da capacidade instalada e expectativa de melhora de vendas: os n\u00fameros divulgados pelo Servi\u00e7o de Apoio \u00e0s Micro e Pequenas Empresas de S\u00e3o Paulo (Sebrae-SP) e Sindicato da Micro e Pequena Ind\u00fastria do Estado de S\u00e3o Paulo (Simpi) mostram sinais de uma retomada lenta, embora constante, do setor que responde por 20% do Produto Interno Bruto (PIB) nacional e emprega 67% dos trabalhadores no estado de S\u00e3o Paulo. <\/P><P>De acordo com o levantamento do Sebrae-SP junto a 2,7 mil micro e pequenas empresas de todo o estado, 52 mil novos postos de trabalho foram abertos em outubro de 2004, revelando crescimento de 1,1% em rela\u00e7\u00e3o a setembro. No entanto, de outubro para novembro, houve uma queda de 0,2%, principalmente no interior, ligada ao processo final de safra de culturas permanentes, como arroz. No per\u00edodo de 12 meses (novembro de 2003 a novembro de 2004), o \u00edndice foi positivo e registrou alta de 3,9%. <\/P><P>O faturamento verificado nas pequenas e micros empresas cresceu 1,7% em novembro em compara\u00e7\u00e3o a outubro do ano passado, o que significa uma receita total de R$ 18,5 bilh\u00f5es no m\u00eas. Esse foi o s\u00e9timo m\u00eas consecutivo de recupera\u00e7\u00e3o no faturamento mensal das empresas. Essa retomada aponta para um otimismo dos pequenos empreendedores para o in\u00edcio de 2005. <\/P><P>&#8220;O setor \u00e9 o primeiro a sentir os efeitos das crises econ\u00f4micas e o \u00faltimo a se recuperar, mas esperamos que esse crescimento econ\u00f4mico demonstre consist\u00eancia nos pr\u00f3ximos meses&#8221;, explica o diretor superintendente do Sebrae-SP, Jos\u00e9 Luiz Ricca. <\/P><P><STRONG>Pequena ind\u00fastria <\/STRONG>&#8211; O setor industrial tamb\u00e9m teve um bom desempenho no final do ano passado. Segundo pesquisa realizada pelo Simpi, no m\u00eas de outubro, o uso da capacidade instalada (UCI) nas micros e pequenas ind\u00fastrias cresceu 0,9%. A m\u00e9dia de 69,5% do UCI em outubro, contra 68,6% em setembro foi a mais expressiva nas pesquisas dos \u00faltimos meses. A entidade ainda n\u00e3o tem as estat\u00edsticas de novembro. <\/P><P>O mesmo levantamento apontou melhora dos n\u00fameros do emprego no setor industrial. Na amostra verificada em 118 empresas, 23% contrataram trabalhadores no m\u00eas de outubro contra 14% que abriram vagas em setembro. Em outubro, foram criados 3,9 mil empregos chegando ao total de 985.300 no conjunto das micro e pequenas ind\u00fastrias pesquisadas. <\/P><P>Quanto ao faturamento, houve um aumento de 3,1% contra a queda de 1% verificada em setembro. Esse aumento ocorreu em 37% das pequenas ind\u00fastrias nos resultados de outubro, contra 30% em setembro. <\/P><P>Apesar dos n\u00fameros positivos, Joseph Couri, presidente do Simpi, acredita que a trajet\u00f3ria do emprego \u00e9 mesma de anos anteriores. &#8220;A economia informal gera empregos, mas o setor precisa de financiamento da produ\u00e7\u00e3o e menos burocracia para abrir novos postos de trabalho&#8221;, diz. <\/P><P><STRONG>Com\u00e9rcio e servi\u00e7os<\/STRONG> &#8211; No final do ano passado, os setores de com\u00e9rcio e servi\u00e7os mostraram uma pequena evolu\u00e7\u00e3o. Segundo os dados do Sebrae-SP, o faturamento das empresas do com\u00e9rcio cresceu 1,5% em novembro, se comparado a outubro de 2004. <\/P><P>Segundo o diretor do Instituto de Economia Gast\u00e3o Vidigal, da Associa\u00e7\u00e3o Comercial de S\u00e3o Paulo (ACSP), Marcel Solimeo, somente as grandes redes de lojas tiveram aumento expressivo nas vendas, que foram impulsionadas pelo cr\u00e9dito para os produtos de maior valor, como eletroeletr\u00f4nicos. &#8220;Com a recupera\u00e7\u00e3o da massa salarial observada nos \u00faltimos meses, o pequeno com\u00e9rcio poder\u00e1 vir a ser beneficiado de agora em diante&#8221;, afirma. <\/P><P>Os servi\u00e7os, liderados por transporte, armazenagem e distribui\u00e7\u00e3o de mercadorias, cresceram 6% em novembro, se comparados a outubro de 2004. <\/P><P>A pesquisa do Sebrae-SP tamb\u00e9m mostrou o crescimento do estado. Tanto a regi\u00e3o metropolitana (+1,6%), quanto o ABC (+3,2%) e o interior (+1,8%) tiveram varia\u00e7\u00e3o positiva de outubro para novembro. Mas, apenas o interior registrou receita crescente em novembro: 3,7%. A regi\u00e3o metropolitana teve queda de 2,1% e o ABC, de 9,2%. <\/P><P><STRONG>S\u00e9rgio Ruiz<\/STRONG><\/P><\/p>\n","protected":false},"excerpt":{"rendered":"Mais empregos, aumento do uso da capacidade instalada e expectativa de melhora de vendas: os n\u00fameros divulgados pelo Servi\u00e7o de Apoio \u00e0s Micro \n<a class=\"moretag\" href=\"https:\/\/www.aceguarulhos.com.br\/blog\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\/\"> [...]<\/a>","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-28996","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pequena empresa cresce, mas a custos altos e ritmo lento - ACE-Guarulhos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aceguarulhos.com.br\/blog\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pequena empresa cresce, mas a custos altos e ritmo lento - ACE-Guarulhos\" \/>\n<meta property=\"og:description\" content=\"Mais empregos, aumento do uso da capacidade instalada e expectativa de melhora de vendas: os n\u00fameros divulgados pelo Servi\u00e7o de Apoio \u00e0s Micro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aceguarulhos.com.br\/blog\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\/\" \/>\n<meta property=\"og:site_name\" content=\"ACE-Guarulhos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aceguarulhos\/\" \/>\n<meta property=\"article:published_time\" content=\"2005-01-10T07:57:03+00:00\" \/>\n<meta name=\"author\" content=\"Assessoria de Imprensa ACE-Guarulhos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Assessoria de Imprensa ACE-Guarulhos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\\\/\"},\"author\":{\"name\":\"Assessoria de Imprensa ACE-Guarulhos\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/6983b51bad37489989e4f09698c26237\"},\"headline\":\"Pequena empresa cresce, mas a custos altos e ritmo lento\",\"datePublished\":\"2005-01-10T07:57:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\\\/\"},\"wordCount\":653,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\\\/\",\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\\\/\",\"name\":\"Pequena empresa cresce, mas a custos altos e ritmo lento - ACE-Guarulhos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#website\"},\"datePublished\":\"2005-01-10T07:57:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pequena empresa cresce, mas a custos altos e ritmo lento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/\",\"name\":\"ACE-Guarulhos\",\"description\":\"A ACE-Guarulhos \u00e9 uma associa\u00e7\u00e3o que ap\u00f3ia os empres\u00e1rios guarulhenses atrav\u00e9s da representa\u00e7\u00e3o, da gera\u00e7\u00e3o de neg\u00f3cios e presta\u00e7\u00e3o de servi\u00e7os.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#organization\",\"name\":\"ACE-Guarulhos\",\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-aceguarulhos-2018.png\",\"contentUrl\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-aceguarulhos-2018.png\",\"width\":419,\"height\":76,\"caption\":\"ACE-Guarulhos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aceguarulhos\\\/\",\"https:\\\/\\\/br.linkedin.com\\\/in\\\/ace-guarulhos-b9a97093\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/aceguarulhos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/6983b51bad37489989e4f09698c26237\",\"name\":\"Assessoria de Imprensa ACE-Guarulhos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g\",\"caption\":\"Assessoria de Imprensa ACE-Guarulhos\"},\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/author\\\/assessoria-de-imprensa-ace-guarulhos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pequena empresa cresce, mas a custos altos e ritmo lento - ACE-Guarulhos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aceguarulhos.com.br\/blog\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\/","og_locale":"pt_BR","og_type":"article","og_title":"Pequena empresa cresce, mas a custos altos e ritmo lento - ACE-Guarulhos","og_description":"Mais empregos, aumento do uso da capacidade instalada e expectativa de melhora de vendas: os n\u00fameros divulgados pelo Servi\u00e7o de Apoio \u00e0s Micro","og_url":"https:\/\/www.aceguarulhos.com.br\/blog\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\/","og_site_name":"ACE-Guarulhos","article_publisher":"https:\/\/www.facebook.com\/aceguarulhos\/","article_published_time":"2005-01-10T07:57:03+00:00","author":"Assessoria de Imprensa ACE-Guarulhos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Assessoria de Imprensa ACE-Guarulhos","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\/#article","isPartOf":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\/"},"author":{"name":"Assessoria de Imprensa ACE-Guarulhos","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#\/schema\/person\/6983b51bad37489989e4f09698c26237"},"headline":"Pequena empresa cresce, mas a custos altos e ritmo lento","datePublished":"2005-01-10T07:57:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\/"},"wordCount":653,"commentCount":0,"publisher":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\/","url":"https:\/\/www.aceguarulhos.com.br\/blog\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\/","name":"Pequena empresa cresce, mas a custos altos e ritmo lento - ACE-Guarulhos","isPartOf":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#website"},"datePublished":"2005-01-10T07:57:03+00:00","breadcrumb":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aceguarulhos.com.br\/blog\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/pequena-empresa-cresce-mas-a-custos-altos-e-ritmo-lento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.aceguarulhos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Pequena empresa cresce, mas a custos altos e ritmo lento"}]},{"@type":"WebSite","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#website","url":"https:\/\/www.aceguarulhos.com.br\/blog\/","name":"ACE-Guarulhos","description":"A ACE-Guarulhos \u00e9 uma associa\u00e7\u00e3o que ap\u00f3ia os empres\u00e1rios guarulhenses atrav\u00e9s da representa\u00e7\u00e3o, da gera\u00e7\u00e3o de neg\u00f3cios e presta\u00e7\u00e3o de servi\u00e7os.","publisher":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aceguarulhos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#organization","name":"ACE-Guarulhos","url":"https:\/\/www.aceguarulhos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-content\/uploads\/2017\/12\/logo-aceguarulhos-2018.png","contentUrl":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-content\/uploads\/2017\/12\/logo-aceguarulhos-2018.png","width":419,"height":76,"caption":"ACE-Guarulhos"},"image":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aceguarulhos\/","https:\/\/br.linkedin.com\/in\/ace-guarulhos-b9a97093","https:\/\/www.youtube.com\/user\/aceguarulhos"]},{"@type":"Person","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#\/schema\/person\/6983b51bad37489989e4f09698c26237","name":"Assessoria de Imprensa ACE-Guarulhos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g","caption":"Assessoria de Imprensa ACE-Guarulhos"},"url":"https:\/\/www.aceguarulhos.com.br\/blog\/author\/assessoria-de-imprensa-ace-guarulhos\/"}]}},"wps_subtitle":"","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/posts\/28996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=28996"}],"version-history":[{"count":0,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/posts\/28996\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=28996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=28996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=28996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}