{"id":28664,"date":"2004-09-22T11:02:19","date_gmt":"2004-09-22T11:02:19","guid":{"rendered":"http:\/\/www.aceguarulhos.com.br\/blog\/?p=28664"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-30T03:00:00","slug":"varejo-perde-vendas-pela-falta-de-produtos","status":"publish","type":"post","link":"https:\/\/www.aceguarulhos.com.br\/blog\/varejo-perde-vendas-pela-falta-de-produtos\/","title":{"rendered":"Varejo perde vendas pela falta de produtos"},"content":{"rendered":"<p><P>O varejo perde 8% de vendas pela falta da marca de prefer\u00eancia do consumidor no momento da compra e suas causas, problema conhecido como ruptura. O resultado foi apontado em um estudo realizado pela Associa\u00e7\u00e3o ECR Brasil, em parceria com a Associa\u00e7\u00e3o Brasileira de Supermercados (Abras) e a empresa de pesquisas ACNielsen. <\/P><P>De acordo com Claudio Czapski, superintendente da ECR Brasil, do total de 528 itens pesquisados, todos de marcas l\u00edderes de vendas, 8% n\u00e3o foram encontrados pelo consumidor no momento da compra. &#8220;As principais causas da falta dos produtos apontadas pelos respons\u00e1veis das lojas foram atraso da entrega do centro de distribui\u00e7\u00e3o do varejo para a loja (27,5%), g\u00f4ndola n\u00e3o reabastecida pelo promotor (14,1%) e o fato da central de compras estar negociando com o fabricante (8,2%)&#8221;, afirma Czapski. <\/P><P><STRONG>Impacto diferente<\/STRONG> &#8211; Ele chama aten\u00e7\u00e3o, entretanto, ao fato da rea\u00e7\u00e3o do consumidor mudar de acordo com a categoria do produto em falta. Em m\u00e9dia, 53% dos consumidores compram outra marca e 37% procuram a marca de sua prefer\u00eancia em outra loja. O estudo tamb\u00e9m detectou que os extremos do comportamento do brasileiro referem-se aos itens \u00f3leo de cozinha: 69% dos consumidores disseram que compram outra marca; e produtos de higiene pessoal: 51% dos entrevistados afirmaram que procuram a marca de sua prefer\u00eancia em outro lugar. <\/P><P>&#8220;Muitas vezes, dependendo da import\u00e2ncia do produto que pretendia comprar, o consumidor abandona na loja o carrinho de compras com todas as outras mercadorias que havia adquirido, em fun\u00e7\u00e3o de um produto que n\u00e3o tenha encontrado&#8221;, alerta o superintendente da ECR Brasil. Um exemplo \u00e9 o chocolate: 17% dos consumidores disseram desistir da compra se n\u00e3o encontram a marca preferida. <\/P><P>Entre os segmentos pesquisados, o que apresentou o maior \u00edndice de ruptura foi o de produtos de bazar, com 9%. J\u00e1 o item mercearia ficou com 8,3%. Entretanto, Czapski chama aten\u00e7\u00e3o ao fato dos produtos desse segmento representarem 48% das vendas. <\/P><P>De acordo com o superintendente da ECR Brasil, os empres\u00e1rios e gestores do varejo podem usar o \u00edndice como uma refer\u00eancia para comparar os pontos de ruptura nas categorias de maior representatividade das suas lojas com a m\u00e9dia do mercado, corrigir as falhas que provocam o problema e aumentar a efici\u00eancia dos processos. <\/P><P><STRONG>Coleta<\/STRONG> &#8211; O trabalho de campo foi realizado em 188 lojas de auto-servi\u00e7o da Grande S\u00e3o Paulo e Grande Rio de Janeiro, das quais 92 delas com 5 a 19 check outs (caixas) e 96 com 20 ou mais check outs. Para cada item ausente na \u00e1rea de vendas, foi pesquisada a causa do problema e em que ponto ele se encontrava ao longo da cadeia de abastecimento. <\/P><P><STRONG>Patr\u00edcia B\u00fcll<\/STRONG><\/P><\/p>\n","protected":false},"excerpt":{"rendered":"O varejo perde 8% de vendas pela falta da marca de prefer\u00eancia do consumidor no momento da compra e suas causas, problema conhecido \n<a class=\"moretag\" href=\"https:\/\/www.aceguarulhos.com.br\/blog\/varejo-perde-vendas-pela-falta-de-produtos\/\"> [...]<\/a>","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-28664","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Varejo perde vendas pela falta de produtos - ACE-Guarulhos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aceguarulhos.com.br\/blog\/varejo-perde-vendas-pela-falta-de-produtos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Varejo perde vendas pela falta de produtos - ACE-Guarulhos\" \/>\n<meta property=\"og:description\" content=\"O varejo perde 8% de vendas pela falta da marca de prefer\u00eancia do consumidor no momento da compra e suas causas, problema conhecido\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aceguarulhos.com.br\/blog\/varejo-perde-vendas-pela-falta-de-produtos\/\" \/>\n<meta property=\"og:site_name\" content=\"ACE-Guarulhos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aceguarulhos\/\" \/>\n<meta property=\"article:published_time\" content=\"2004-09-22T11:02:19+00:00\" \/>\n<meta name=\"author\" content=\"Assessoria de Imprensa ACE-Guarulhos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Assessoria de Imprensa ACE-Guarulhos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/varejo-perde-vendas-pela-falta-de-produtos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/varejo-perde-vendas-pela-falta-de-produtos\\\/\"},\"author\":{\"name\":\"Assessoria de Imprensa ACE-Guarulhos\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/6983b51bad37489989e4f09698c26237\"},\"headline\":\"Varejo perde vendas pela falta de produtos\",\"datePublished\":\"2004-09-22T11:02:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/varejo-perde-vendas-pela-falta-de-produtos\\\/\"},\"wordCount\":454,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/varejo-perde-vendas-pela-falta-de-produtos\\\/\",\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/varejo-perde-vendas-pela-falta-de-produtos\\\/\",\"name\":\"Varejo perde vendas pela falta de produtos - ACE-Guarulhos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#website\"},\"datePublished\":\"2004-09-22T11:02:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/varejo-perde-vendas-pela-falta-de-produtos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/varejo-perde-vendas-pela-falta-de-produtos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/varejo-perde-vendas-pela-falta-de-produtos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Varejo perde vendas pela falta de produtos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/\",\"name\":\"ACE-Guarulhos\",\"description\":\"A ACE-Guarulhos \u00e9 uma associa\u00e7\u00e3o que ap\u00f3ia os empres\u00e1rios guarulhenses atrav\u00e9s da representa\u00e7\u00e3o, da gera\u00e7\u00e3o de neg\u00f3cios e presta\u00e7\u00e3o de servi\u00e7os.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#organization\",\"name\":\"ACE-Guarulhos\",\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-aceguarulhos-2018.png\",\"contentUrl\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-aceguarulhos-2018.png\",\"width\":419,\"height\":76,\"caption\":\"ACE-Guarulhos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aceguarulhos\\\/\",\"https:\\\/\\\/br.linkedin.com\\\/in\\\/ace-guarulhos-b9a97093\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/aceguarulhos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/6983b51bad37489989e4f09698c26237\",\"name\":\"Assessoria de Imprensa ACE-Guarulhos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g\",\"caption\":\"Assessoria de Imprensa ACE-Guarulhos\"},\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/author\\\/assessoria-de-imprensa-ace-guarulhos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Varejo perde vendas pela falta de produtos - ACE-Guarulhos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aceguarulhos.com.br\/blog\/varejo-perde-vendas-pela-falta-de-produtos\/","og_locale":"pt_BR","og_type":"article","og_title":"Varejo perde vendas pela falta de produtos - ACE-Guarulhos","og_description":"O varejo perde 8% de vendas pela falta da marca de prefer\u00eancia do consumidor no momento da compra e suas causas, problema conhecido","og_url":"https:\/\/www.aceguarulhos.com.br\/blog\/varejo-perde-vendas-pela-falta-de-produtos\/","og_site_name":"ACE-Guarulhos","article_publisher":"https:\/\/www.facebook.com\/aceguarulhos\/","article_published_time":"2004-09-22T11:02:19+00:00","author":"Assessoria de Imprensa ACE-Guarulhos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Assessoria de Imprensa ACE-Guarulhos","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/varejo-perde-vendas-pela-falta-de-produtos\/#article","isPartOf":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/varejo-perde-vendas-pela-falta-de-produtos\/"},"author":{"name":"Assessoria de Imprensa ACE-Guarulhos","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#\/schema\/person\/6983b51bad37489989e4f09698c26237"},"headline":"Varejo perde vendas pela falta de produtos","datePublished":"2004-09-22T11:02:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/varejo-perde-vendas-pela-falta-de-produtos\/"},"wordCount":454,"commentCount":0,"publisher":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/varejo-perde-vendas-pela-falta-de-produtos\/","url":"https:\/\/www.aceguarulhos.com.br\/blog\/varejo-perde-vendas-pela-falta-de-produtos\/","name":"Varejo perde vendas pela falta de produtos - ACE-Guarulhos","isPartOf":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#website"},"datePublished":"2004-09-22T11:02:19+00:00","breadcrumb":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/varejo-perde-vendas-pela-falta-de-produtos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aceguarulhos.com.br\/blog\/varejo-perde-vendas-pela-falta-de-produtos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/varejo-perde-vendas-pela-falta-de-produtos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.aceguarulhos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Varejo perde vendas pela falta de produtos"}]},{"@type":"WebSite","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#website","url":"https:\/\/www.aceguarulhos.com.br\/blog\/","name":"ACE-Guarulhos","description":"A ACE-Guarulhos \u00e9 uma associa\u00e7\u00e3o que ap\u00f3ia os empres\u00e1rios guarulhenses atrav\u00e9s da representa\u00e7\u00e3o, da gera\u00e7\u00e3o de neg\u00f3cios e presta\u00e7\u00e3o de servi\u00e7os.","publisher":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aceguarulhos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#organization","name":"ACE-Guarulhos","url":"https:\/\/www.aceguarulhos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-content\/uploads\/2017\/12\/logo-aceguarulhos-2018.png","contentUrl":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-content\/uploads\/2017\/12\/logo-aceguarulhos-2018.png","width":419,"height":76,"caption":"ACE-Guarulhos"},"image":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aceguarulhos\/","https:\/\/br.linkedin.com\/in\/ace-guarulhos-b9a97093","https:\/\/www.youtube.com\/user\/aceguarulhos"]},{"@type":"Person","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#\/schema\/person\/6983b51bad37489989e4f09698c26237","name":"Assessoria de Imprensa ACE-Guarulhos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g","caption":"Assessoria de Imprensa ACE-Guarulhos"},"url":"https:\/\/www.aceguarulhos.com.br\/blog\/author\/assessoria-de-imprensa-ace-guarulhos\/"}]}},"wps_subtitle":"","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/posts\/28664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=28664"}],"version-history":[{"count":0,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/posts\/28664\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=28664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=28664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=28664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}