{"id":28652,"date":"2004-09-17T17:24:23","date_gmt":"2004-09-17T17:24:23","guid":{"rendered":"http:\/\/www.aceguarulhos.com.br\/blog\/?p=28652"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-30T03:00:00","slug":"pequenos-podem-e-devem-anunciar","status":"publish","type":"post","link":"https:\/\/www.aceguarulhos.com.br\/blog\/pequenos-podem-e-devem-anunciar\/","title":{"rendered":"Pequenos podem e devem anunciar"},"content":{"rendered":"<p><P>\u00c0 primeira vista, publicidade \u00e9 assunto que se discute apenas dentro de grandes empresas. Mas a realidade \u00e9 outra. Para cada porte de empreendimento h\u00e1 um prestador de servi\u00e7os compat\u00edvel e interessado em criar um ambiente de neg\u00f3cios t\u00e3o amplo quanto aquele estruturado pelas grandes. <\/P><P>No caso espec\u00edfico da propaganda, o mesmo acontece. Existem ag\u00eancias especializadas em atender a demanda de projetos enxutos e eficientes, o que na pr\u00e1tica se traduz em custos compat\u00edveis ao faturamento das micro empresas. <\/P><P><STRONG>Marketing de guerrilha<\/STRONG> &#8211; Luciano Santos, propriet\u00e1rio da Blend Comunica\u00e7\u00e3o, sediada na capital paulista, conhece bem as condi\u00e7\u00f5es dos neg\u00f3cios pequenos. Ap\u00f3s atuar como publicit\u00e1rio em ag\u00eancias e praticar suas habilidades em promo\u00e7\u00e3o em prol de uma estamparia que criou, resolveu voltar ao ramo do marketing montando a pr\u00f3pria ag\u00eancia h\u00e1 quatro anos. &#8220;A pequena empresa deve fazer o que chamamos de &#8220;marketing de guerrilha&#39;, ou seja, usar seu conhecimento e for\u00e7a local para conquistar o consumidor da regi\u00e3o&#8221;, afirma. <\/P><P>Para ele, as ag\u00eancias de pequeno e m\u00e9dio porte t\u00eam pr\u00e1tica na busca de m\u00eddias especializadas e outros recursos de comunica\u00e7\u00e3o que cabem no bolso do empres\u00e1rio. &#8220;H\u00e1 jornais, revistas e sites de bairros que s\u00e3o lidos pela popula\u00e7\u00e3o que busca servi\u00e7os e produtos na regi\u00e3o em que mora. Se o objeto comercializado \u00e9 voltado a um p\u00fablico espec\u00edfico, h\u00e1 canais de comunica\u00e7\u00e3o com esta comunidade, como associa\u00e7\u00f5es e grupos de discuss\u00e3o. O nosso trabalho \u00e9 reconhecer estes canais e desenvolver projetos de comunica\u00e7\u00e3o&#8221;, diz. O publicit\u00e1rio cita como exemplo a sinaliza\u00e7\u00e3o que traz informa\u00e7\u00f5es de utilidade p\u00fablica e menciona o estabelecimento comercial ao mesmo tempo. <\/P><P><STRONG>Publicidade n\u00e3o \u00e9 despesa<\/STRONG> &#8211; Santos acredita que sempre h\u00e1 uma solu\u00e7\u00e3o cab\u00edvel. &#8220;O custo da publicidade n\u00e3o deve ser visto como despesa, mas como investimento. O retorno existir\u00e1 para um projeto de comunica\u00e7\u00e3o bem planejado&#8221;, diz. <\/P><P>A ABC&#038;Z Publicidade, tamb\u00e9m de S\u00e3o Paulo, produz campanhas de publicidade que apresentam custos m\u00e9dios entre R$ 10 mil e R$ 20 mil. &#8220;Muitas vezes o pequeno empreendedor cria um fundo de propaganda para a empresa, economiza dinheiro e aplica na m\u00eddia errada. \u00c9 comum ouvir de empres\u00e1rios que investiram, por exemplo, em revistas como a Veja S\u00e3o Paulo ou os jornais Folha de S\u00e3o Paulo ou Estado de S\u00e3o Paulo e depois n\u00e3o foram capazes de atender \u00e0 demanda de servi\u00e7o gerada pela publicidade&#8221;, explica Marcel Antunes, publicit\u00e1rio e s\u00f3cio-diretor da ag\u00eancia ABC&#038;Z. <\/P><P><STRONG>Ve\u00edculo certo<\/STRONG> &#8211; Ele afirma que a estrutura da corpora\u00e7\u00e3o a ser divulgada precisa ser levada em conta no momento da escolha do canal de comunica\u00e7\u00e3o. &#8220;Uma \u00fanica linha telef\u00f4nica para atender clientes e poucos colaboradores \u00e9 mau sinal para o empreendedor que espera obter retorno de an\u00fancios em grandes ve\u00edculos de comunica\u00e7\u00e3o. Corre-se o risco de n\u00e3o conseguir atender \u00e0 demanda e ficar com a imagem desqualificada&#8221;, afirma. <\/P><P><STRONG>Simples<\/STRONG> &#8211; Antunes diz que a\u00e7\u00f5es simples como produ\u00e7\u00e3o cat\u00e1logos e panfletos sob a orienta\u00e7\u00e3o de especialistas em marketing d\u00e3o \u00f3timo retorno para uma pequena empresa. &#8220;Toda e qualquer a\u00e7\u00e3o que visa anunciar em paralelo com propagandas torna-se uma arma poderosa para a conquista e o reconhecimento do consumidor&#8221; , diz o publicit\u00e1rio. Nessa linha, a Associa\u00e7\u00e3o Brasileira das Ag\u00eancias de Publicidade, Abap, lan\u00e7ou uma cartilha com dicas para as pequenas e m\u00e9dias empresas que desejam anunciar. <\/P><P><STRONG>Juliana de Moraes<\/STRONG><\/P><\/p>\n","protected":false},"excerpt":{"rendered":"\u00c0 primeira vista, publicidade \u00e9 assunto que se discute apenas dentro de grandes empresas. Mas a realidade \u00e9 outra. Para cada porte de \n<a class=\"moretag\" href=\"https:\/\/www.aceguarulhos.com.br\/blog\/pequenos-podem-e-devem-anunciar\/\"> [...]<\/a>","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-28652","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pequenos podem e devem anunciar - ACE-Guarulhos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aceguarulhos.com.br\/blog\/pequenos-podem-e-devem-anunciar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pequenos podem e devem anunciar - ACE-Guarulhos\" \/>\n<meta property=\"og:description\" content=\"\u00c0 primeira vista, publicidade \u00e9 assunto que se discute apenas dentro de grandes empresas. Mas a realidade \u00e9 outra. Para cada porte de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aceguarulhos.com.br\/blog\/pequenos-podem-e-devem-anunciar\/\" \/>\n<meta property=\"og:site_name\" content=\"ACE-Guarulhos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aceguarulhos\/\" \/>\n<meta property=\"article:published_time\" content=\"2004-09-17T17:24:23+00:00\" \/>\n<meta name=\"author\" content=\"Assessoria de Imprensa ACE-Guarulhos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Assessoria de Imprensa ACE-Guarulhos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/pequenos-podem-e-devem-anunciar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/pequenos-podem-e-devem-anunciar\\\/\"},\"author\":{\"name\":\"Assessoria de Imprensa ACE-Guarulhos\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/6983b51bad37489989e4f09698c26237\"},\"headline\":\"Pequenos podem e devem anunciar\",\"datePublished\":\"2004-09-17T17:24:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/pequenos-podem-e-devem-anunciar\\\/\"},\"wordCount\":617,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/pequenos-podem-e-devem-anunciar\\\/\",\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/pequenos-podem-e-devem-anunciar\\\/\",\"name\":\"Pequenos podem e devem anunciar - ACE-Guarulhos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#website\"},\"datePublished\":\"2004-09-17T17:24:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/pequenos-podem-e-devem-anunciar\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/pequenos-podem-e-devem-anunciar\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/pequenos-podem-e-devem-anunciar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pequenos podem e devem anunciar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/\",\"name\":\"ACE-Guarulhos\",\"description\":\"A ACE-Guarulhos \u00e9 uma associa\u00e7\u00e3o que ap\u00f3ia os empres\u00e1rios guarulhenses atrav\u00e9s da representa\u00e7\u00e3o, da gera\u00e7\u00e3o de neg\u00f3cios e presta\u00e7\u00e3o de servi\u00e7os.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#organization\",\"name\":\"ACE-Guarulhos\",\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-aceguarulhos-2018.png\",\"contentUrl\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-aceguarulhos-2018.png\",\"width\":419,\"height\":76,\"caption\":\"ACE-Guarulhos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aceguarulhos\\\/\",\"https:\\\/\\\/br.linkedin.com\\\/in\\\/ace-guarulhos-b9a97093\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/aceguarulhos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/6983b51bad37489989e4f09698c26237\",\"name\":\"Assessoria de Imprensa ACE-Guarulhos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g\",\"caption\":\"Assessoria de Imprensa ACE-Guarulhos\"},\"url\":\"https:\\\/\\\/www.aceguarulhos.com.br\\\/blog\\\/author\\\/assessoria-de-imprensa-ace-guarulhos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pequenos podem e devem anunciar - ACE-Guarulhos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aceguarulhos.com.br\/blog\/pequenos-podem-e-devem-anunciar\/","og_locale":"pt_BR","og_type":"article","og_title":"Pequenos podem e devem anunciar - ACE-Guarulhos","og_description":"\u00c0 primeira vista, publicidade \u00e9 assunto que se discute apenas dentro de grandes empresas. Mas a realidade \u00e9 outra. Para cada porte de","og_url":"https:\/\/www.aceguarulhos.com.br\/blog\/pequenos-podem-e-devem-anunciar\/","og_site_name":"ACE-Guarulhos","article_publisher":"https:\/\/www.facebook.com\/aceguarulhos\/","article_published_time":"2004-09-17T17:24:23+00:00","author":"Assessoria de Imprensa ACE-Guarulhos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Assessoria de Imprensa ACE-Guarulhos","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/pequenos-podem-e-devem-anunciar\/#article","isPartOf":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/pequenos-podem-e-devem-anunciar\/"},"author":{"name":"Assessoria de Imprensa ACE-Guarulhos","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#\/schema\/person\/6983b51bad37489989e4f09698c26237"},"headline":"Pequenos podem e devem anunciar","datePublished":"2004-09-17T17:24:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/pequenos-podem-e-devem-anunciar\/"},"wordCount":617,"commentCount":0,"publisher":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/pequenos-podem-e-devem-anunciar\/","url":"https:\/\/www.aceguarulhos.com.br\/blog\/pequenos-podem-e-devem-anunciar\/","name":"Pequenos podem e devem anunciar - ACE-Guarulhos","isPartOf":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#website"},"datePublished":"2004-09-17T17:24:23+00:00","breadcrumb":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/pequenos-podem-e-devem-anunciar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aceguarulhos.com.br\/blog\/pequenos-podem-e-devem-anunciar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/pequenos-podem-e-devem-anunciar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.aceguarulhos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Pequenos podem e devem anunciar"}]},{"@type":"WebSite","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#website","url":"https:\/\/www.aceguarulhos.com.br\/blog\/","name":"ACE-Guarulhos","description":"A ACE-Guarulhos \u00e9 uma associa\u00e7\u00e3o que ap\u00f3ia os empres\u00e1rios guarulhenses atrav\u00e9s da representa\u00e7\u00e3o, da gera\u00e7\u00e3o de neg\u00f3cios e presta\u00e7\u00e3o de servi\u00e7os.","publisher":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aceguarulhos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#organization","name":"ACE-Guarulhos","url":"https:\/\/www.aceguarulhos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-content\/uploads\/2017\/12\/logo-aceguarulhos-2018.png","contentUrl":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-content\/uploads\/2017\/12\/logo-aceguarulhos-2018.png","width":419,"height":76,"caption":"ACE-Guarulhos"},"image":{"@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aceguarulhos\/","https:\/\/br.linkedin.com\/in\/ace-guarulhos-b9a97093","https:\/\/www.youtube.com\/user\/aceguarulhos"]},{"@type":"Person","@id":"https:\/\/www.aceguarulhos.com.br\/blog\/#\/schema\/person\/6983b51bad37489989e4f09698c26237","name":"Assessoria de Imprensa ACE-Guarulhos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/707f3fadd6918afeb64173ab22d8a8cb0676953098a4f31ff36dc2b4c699ef6a?s=96&d=mm&r=g","caption":"Assessoria de Imprensa ACE-Guarulhos"},"url":"https:\/\/www.aceguarulhos.com.br\/blog\/author\/assessoria-de-imprensa-ace-guarulhos\/"}]}},"wps_subtitle":"","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/posts\/28652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=28652"}],"version-history":[{"count":0,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/posts\/28652\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=28652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=28652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aceguarulhos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=28652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}